{"id":123,"count":2,"description":"","link":"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/","name":"glass window","slug":"glass-window","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>glass window Archives - Okna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"glass window Archives - Okna\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/\" \/>\n<meta property=\"og:site_name\" content=\"Okna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/\",\"url\":\"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/\",\"name\":\"glass window Archives - Okna\",\"isPartOf\":{\"@id\":\"https:\/\/oknadesigns.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/oknadesigns.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"glass window\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oknadesigns.com\/blog\/#website\",\"url\":\"https:\/\/oknadesigns.com\/blog\/\",\"name\":\"Okna\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oknadesigns.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"glass window Archives - Okna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/","og_locale":"en_US","og_type":"article","og_title":"glass window Archives - Okna","og_url":"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/","og_site_name":"Okna","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/","url":"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/","name":"glass window Archives - Okna","isPartOf":{"@id":"https:\/\/oknadesigns.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/oknadesigns.com\/blog\/category\/glass-window\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oknadesigns.com\/blog\/"},{"@type":"ListItem","position":2,"name":"glass window"}]},{"@type":"WebSite","@id":"https:\/\/oknadesigns.com\/blog\/#website","url":"https:\/\/oknadesigns.com\/blog\/","name":"Okna","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oknadesigns.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/oknadesigns.com\/blog\/wp-json\/wp\/v2\/categories\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oknadesigns.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/oknadesigns.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/oknadesigns.com\/blog\/wp-json\/wp\/v2\/posts?categories=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}