{"id":198,"count":2,"description":"","link":"https:\/\/oknadesigns.com\/blog\/tag\/luxury-sliding-doors-india\/","name":"luxury sliding doors india","slug":"luxury-sliding-doors-india","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>luxury sliding doors india Archives - Okna<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"luxury sliding doors india Archives - Okna\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oknadesigns.com\/blog\/tag\/luxury-sliding-doors-india\/\" \/>\n<meta property=\"og:site_name\" content=\"Okna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/oknadesigns.com\/blog\/tag\/luxury-sliding-doors-india\/\",\"url\":\"https:\/\/oknadesigns.com\/blog\/tag\/luxury-sliding-doors-india\/\",\"name\":\"luxury sliding doors india Archives - Okna\",\"isPartOf\":{\"@id\":\"https:\/\/oknadesigns.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/oknadesigns.com\/blog\/tag\/luxury-sliding-doors-india\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oknadesigns.com\/blog\/tag\/luxury-sliding-doors-india\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/oknadesigns.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"luxury sliding doors india\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oknadesigns.com\/blog\/#website\",\"url\":\"https:\/\/oknadesigns.com\/blog\/\",\"name\":\"Okna\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oknadesigns.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"luxury sliding doors india Archives - Okna","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"luxury sliding doors india Archives - Okna","og_url":"https:\/\/oknadesigns.com\/blog\/tag\/luxury-sliding-doors-india\/","og_site_name":"Okna","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/oknadesigns.com\/blog\/tag\/luxury-sliding-doors-india\/","url":"https:\/\/oknadesigns.com\/blog\/tag\/luxury-sliding-doors-india\/","name":"luxury sliding doors india Archives - Okna","isPartOf":{"@id":"https:\/\/oknadesigns.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/oknadesigns.com\/blog\/tag\/luxury-sliding-doors-india\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/oknadesigns.com\/blog\/tag\/luxury-sliding-doors-india\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oknadesigns.com\/blog\/"},{"@type":"ListItem","position":2,"name":"luxury sliding doors india"}]},{"@type":"WebSite","@id":"https:\/\/oknadesigns.com\/blog\/#website","url":"https:\/\/oknadesigns.com\/blog\/","name":"Okna","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oknadesigns.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/oknadesigns.com\/blog\/wp-json\/wp\/v2\/tags\/198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oknadesigns.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/oknadesigns.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/oknadesigns.com\/blog\/wp-json\/wp\/v2\/posts?tags=198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}